{"id":1167,"date":"2026-09-01T23:40:34","date_gmt":"2026-09-01T23:40:34","guid":{"rendered":"https:\/\/observar.org.ar\/web\/index.php\/2026\/09\/01\/estudio-liderado-por-cientifico-del-conicet-concluye-que-la-explicacion-clasica-de-la-depresion-por-consanguinidad-es-insuficiente\/"},"modified":"2026-09-01T23:40:34","modified_gmt":"2026-09-01T23:40:34","slug":"estudio-liderado-por-cientifico-del-conicet-concluye-que-la-explicacion-clasica-de-la-depresion-por-consanguinidad-es-insuficiente","status":"publish","type":"post","link":"https:\/\/observar.org.ar\/web\/index.php\/2026\/09\/01\/estudio-liderado-por-cientifico-del-conicet-concluye-que-la-explicacion-clasica-de-la-depresion-por-consanguinidad-es-insuficiente\/","title":{"rendered":"Estudio liderado por cient\u00edfico del CONICET concluye que la explicaci\u00f3n cl\u00e1sica de la depresi\u00f3n por consanguinidad es insuficiente"},"content":{"rendered":"<h2>Estudio liderado por cient\u00edfico del CONICET concluye que la explicaci\u00f3n cl\u00e1sica de la depresi\u00f3n por consanguinidad es insuficiente<\/h2>\n<p><strong>1 de septiembre de 2026<br \/>\n\t\t\t\t\t\t\t\t\t\tEstudio liderado por cient\u00edfico del CONICET concluye que la explicaci\u00f3n cl\u00e1sica de la depresi\u00f3n por consanguinidad es insuficiente<\/p>\n<p>    \t\t\t\t\t\t\t\t\t\tEl trabajo fue publicado en la revista Evolution Letters.<\/strong><\/p>\n<p>El trabajo, realizado junto a investigadores del CNRS (Francia) y publicado en la revista Evolution Letters, aporta la primera evidencia experimental de que la menor capacidad para sobrevivir y reproducirse que presentan los descendientes de individuos emparentados no ser\u00eda atribuible \u00fanicamente a razones gen\u00e9ticas. Los resultados abren una nueva perspectiva sobre el posible papel de mecanismos epigen\u00e9ticos en la evoluci\u00f3n y la conservaci\u00f3n de las especies.<\/p>\n<p>Compartir en  redes sociales<\/p>\n<p>La pregunta acerca de por qu\u00e9 la descendencia de individuos emparentados suele presentar menor capacidad para sobrevivir o reproducirse demanda la atenci\u00f3n de los bi\u00f3logos desde hace m\u00e1s de un siglo. La explicaci\u00f3n cl\u00e1sica sostiene que la consanguinidad aumenta la probabilidad de que estos individuos hereden dos copias recesivas o defectuosas del mismo gen, una de cada progenitor. Dado que los parientes tienen en com\u00fan buena parte de su informaci\u00f3n gen\u00e9tica, tambi\u00e9n tienen m\u00e1s probabilidades de compartir mutaciones perjudiciales en los mismos genes. Cuando ambas coinciden en la descendencia, sus efectos negativos se manifiestan.<\/p>\n<p>Sin embargo, esta explicaci\u00f3n depende de un supuesto fundamental: que esos efectos negativos s\u00f3lo pueden aparecer porque dentro de las distintas especies existen variaciones gen\u00e9ticas entre los individuos, es decir, porque algunos portan en sus ADN variantes perjudiciales -transmisibles a la descendencia-\u00a0 que otros no comparten. Si esas variaciones desaparecieran y todos los individuos de una especie compartieran pr\u00e1cticamente el mismo genotipo, la depresi\u00f3n por consanguinidad deber\u00eda desaparecer. No obstante, esa predicci\u00f3n nunca hab\u00eda sido puesta a prueba de manera directa. Ahora, un estudio liderado por Nicol\u00e1s Bonel, investigador del CONICET en el Centro de Recursos Naturales Renovables de la Zona Semi\u00e1rida (CERZOS, CONICET-UNS), y Patrice David, del Centre d\u2019\u00c9cologie Fonctionnelle et \u00c9volutive (CEFE-CNRS, Francia), muestra que esa explicaci\u00f3n es insuficiente para describir todos los procesos involucrados. El trabajo fue publicado en la revista Evolution Letters.<\/p>\n<p>\u201cDurante m\u00e1s de un siglo asumimos que la depresi\u00f3n por consanguinidad era exclusivamente una consecuencia de mutaciones delet\u00e9reas que quedaban expuestas al aumentar la homocigosis (la posesi\u00f3n de dos copias id\u00e9nticas de un mismo gen). Nuestro estudio permiti\u00f3 poner esa explicaci\u00f3n a prueba de manera directa. Buscamos responder una pregunta fundamental: \u00bfqu\u00e9 ocurrir\u00eda con la depresi\u00f3n por consanguinidad si se eliminara casi por completo la variaci\u00f3n gen\u00e9tica entre los individuos sin modificar el grado de parentesco entre ellos? Responderla exigi\u00f3 un dise\u00f1o experimental capaz de desacoplar, por primera vez, el parentesco geneal\u00f3gico de la variaci\u00f3n gen\u00e9tica. Los resultados muestran que los efectos negativos de la consanguinidad persisten aun cuando ya no existe variaci\u00f3n gen\u00e9tica que pueda explicar las diferencias observadas. Eso nos obliga a considerar que existen otros mecanismos involucrados en este fen\u00f3meno\u201d, explica Nicol\u00e1s Bonel.<\/p>\n<p>El equipo de investigaci\u00f3n trabaj\u00f3 con Physa acuta, un caracol hermafrodita de agua dulce ampliamente utilizado como organismo modelo en estudios de consanguinidad. Diferentes individuos fueron sometidos a autofecundaci\u00f3n forzada durante 28 generaciones hasta reducir su variaci\u00f3n gen\u00e9tica a niveles casi nulos, obteniendo as\u00ed l\u00edneas experimentales gen\u00e9ticamente uniformes. Luego cruzaron esas l\u00edneas y, con la descendencia gen\u00e9ticamente uniforme resultante, generaron tres tipos de cruzamientos: autofecundaci\u00f3n, fecundaci\u00f3n entre hermanos y fecundaci\u00f3n entre primos.<\/p>\n<p>Si la explicaci\u00f3n cl\u00e1sica fuese suficiente, los tres grupos \u2014con pr\u00e1cticamente el mismo genotipo\u2014 deber\u00edan haber tenido igual posibilidad de sobrevivencia y reproducci\u00f3n. Sin embargo, ocurri\u00f3 lo contrario: la descendencia autofecundada mostr\u00f3 menor supervivencia juvenil, menor tama\u00f1o corporal y menor \u00e9xito reproductivo que la nacida de cruces entre hermanos, y esta \u00faltima tuvo un menor desempe\u00f1o que la de cruces entre primos<\/p>\n<p>Para descartar que esas diferencias se debieran a nuevas mutaciones surgidas durante el experimento, el equipo utiliz\u00f3 modelos de simulaci\u00f3n basados en las tasas de mutaci\u00f3n conocidas para la especie, e incluso multiplic\u00e1ndolas por diez, un escenario biol\u00f3gicamente muy improbable. El modelo no logr\u00f3 reproducir la magnitud del efecto observado. La explicaci\u00f3n gen\u00e9tica cl\u00e1sica segu\u00eda siendo insuficiente.<\/p>\n<p>Para los investigadores, la explicaci\u00f3n m\u00e1s consistente es la participaci\u00f3n de mecanismos compatibles con procesos epigen\u00e9ticos. Es decir, que las epimutaciones \u2014variantes heredables que surgen y revierten con frecuencia mucho mayor que las variaciones gen\u00e9ticas\u2014 tambi\u00e9n contribuyen a la depresi\u00f3n por consanguinidad.<\/p>\n<p>\u201cEl ADN contiene la informaci\u00f3n gen\u00e9tica, pero la epigen\u00e9tica funciona como un conjunto de instrucciones que regulan c\u00f3mo se utiliza esa informaci\u00f3n. Son marcas qu\u00edmicas que pueden activar o silenciar genes sin modificar la secuencia del ADN y, en algunos casos, transmitirse de padres a hijos. Nuestra hip\u00f3tesis es que cuando los gametos provienen de individuos estrechamente emparentados, es m\u00e1s probable que compartan ciertas marcas epigen\u00e9ticas desfavorables, lo que podr\u00eda afectar el desarrollo y el desempe\u00f1o de la descendencia aun cuando la secuencia del ADN sea la misma\u201d, explica Bonel.<\/p>\n<p>Desarrollar un experimento de estas caracter\u00edsticas demand\u00f3 m\u00e1s de una d\u00e9cada de trabajo continuo. \u201cMantener l\u00edneas experimentales durante m\u00e1s de veintiocho generaciones requiri\u00f3 un seguimiento constante y una infraestructura que pudiera sostenerse en el tiempo. Hay preguntas cient\u00edficas que no admiten atajos: necesitan tiempo, continuidad, planificaci\u00f3n y equipos que permitan sostener investigaciones de largo plazo\u201d, destaca el investigador.<\/p>\n<p>Implicancias para la biolog\u00eda evolutiva y la conservaci\u00f3n de las especies<\/p>\n<p>De acuerdo con el investigador, comprender por qu\u00e9 la consanguinidad reduce la capacidad de supervivencia de una poblaci\u00f3n es un tema central para la biolog\u00eda evolutiva, con implicancias directas para la conservaci\u00f3n de especies amenazadas.<\/p>\n<p>Muchas poblaciones peque\u00f1as y aisladas se reproducen entre individuos emparentados debido a la escasez de ejemplares. Hasta ahora, los modelos utilizados para evaluar ese riesgo consideraban principalmente la acumulaci\u00f3n de mutaciones perjudiciales. Los nuevos resultados sugieren que tambi\u00e9n podr\u00edan intervenir mecanismos epigen\u00e9ticos, un aspecto que podr\u00eda incorporarse en futuras investigaciones y estrategias de conservaci\u00f3n.<\/p>\n<p>Para finalizar, Bonel destaca que el hallazgo podr\u00eda aportar nuevas herramientas para programas de cr\u00eda selectiva y mejoramiento gen\u00e9tico, donde la reproducci\u00f3n entre individuos emparentados es una pr\u00e1ctica frecuente para fijar determinadas caracter\u00edsticas y preservar l\u00edneas gen\u00e9ticas.<\/p>\n<p><small>Fuente: <a href=\"https:\/\/www.conicet.gov.ar\/noticias-conicet\/\" target=\"_blank\">https:\/\/www.conicet.gov.ar\/noticias-conicet\/<\/a><\/small><\/p>\n","protected":false},"excerpt":{"rendered":"<p>1 de septiembre de 2026 Estudio liderado por cient\u00edfico del CONICET concluye que la explicaci\u00f3n cl\u00e1sica de la depresi\u00f3n por consanguinidad es insuficiente El trabajo fue publicado en la revista Evolution Letters.<\/p>\n","protected":false},"author":0,"featured_media":1168,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[8],"tags":[],"class_list":["post-1167","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia"],"_links":{"self":[{"href":"https:\/\/observar.org.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/1167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/observar.org.ar\/web\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/observar.org.ar\/web\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/observar.org.ar\/web\/index.php\/wp-json\/wp\/v2\/comments?post=1167"}],"version-history":[{"count":0,"href":"https:\/\/observar.org.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/1167\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/observar.org.ar\/web\/index.php\/wp-json\/wp\/v2\/media\/1168"}],"wp:attachment":[{"href":"https:\/\/observar.org.ar\/web\/index.php\/wp-json\/wp\/v2\/media?parent=1167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/observar.org.ar\/web\/index.php\/wp-json\/wp\/v2\/categories?post=1167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/observar.org.ar\/web\/index.php\/wp-json\/wp\/v2\/tags?post=1167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}